{"id":9469,"count":1,"description":"","link":"https:\/\/multahost.com\/blog\/tag\/vos3000-cdr-log-configuration\/","name":"VOS3000 CDR log configuration","slug":"vos3000-cdr-log-configuration","taxonomy":"post_tag","meta":[],"_links":{"self":[{"href":"https:\/\/multahost.com\/blog\/wp-json\/wp\/v2\/tags\/9469","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/multahost.com\/blog\/wp-json\/wp\/v2\/tags"}],"about":[{"href":"https:\/\/multahost.com\/blog\/wp-json\/wp\/v2\/taxonomies\/post_tag"}],"wp:post_type":[{"href":"https:\/\/multahost.com\/blog\/wp-json\/wp\/v2\/posts?tags=9469"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}