{"id":51,"count":28,"description":"","link":"https:\/\/multahost.com\/blog\/category\/voip-manual-collection\/pdf-manual\/","name":"PDF Manual","slug":"pdf-manual","taxonomy":"category","parent":50,"meta":[],"acf":[],"_links":{"self":[{"href":"https:\/\/multahost.com\/blog\/wp-json\/wp\/v2\/categories\/51","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/multahost.com\/blog\/wp-json\/wp\/v2\/categories"}],"about":[{"href":"https:\/\/multahost.com\/blog\/wp-json\/wp\/v2\/taxonomies\/category"}],"up":[{"embeddable":true,"href":"https:\/\/multahost.com\/blog\/wp-json\/wp\/v2\/categories\/50"}],"wp:post_type":[{"href":"https:\/\/multahost.com\/blog\/wp-json\/wp\/v2\/posts?categories=51"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}